{"id":2509,"date":"2022-08-17T12:46:16","date_gmt":"2022-08-17T17:46:16","guid":{"rendered":"https:\/\/www.creditas.mx\/exponencial\/?p=2509"},"modified":"2026-07-28T11:41:24","modified_gmt":"2026-07-28T17:41:24","slug":"buro-de-credito-malo-como-mejorarlo","status":"publish","type":"post","link":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/","title":{"rendered":"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo?"},"content":{"rendered":"\r\n<p>Seguramente m\u00e1s de una vez has escuchado que &#8220;estar en bur\u00f3 es un problema&#8221; , &#8220;que los bancos ya no te prestar\u00e1n&#8221; o &#8220;es la lista negra de quienes no pagan&#8221;; hoy te explicamos qu\u00e9 es, que tan malo es estar en bur\u00f3 y c\u00f3mo mejorar tu score crediticio si tienes un bur\u00f3 de cr\u00e9dito malo.<\/p>\r\n\r\n\r\n\r\n<p>Despu\u00e9s de este art\u00edculo conocer\u00e1s mucho m\u00e1s de esta herramienta y el para qu\u00e9 sirve.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es el bur\u00f3 de cr\u00e9dito?<\/h2>\r\n\r\n\r\n\r\n<p>El bur\u00f3 de cr\u00e9dito es un registro de todas las personas que han pedido alg\u00fan tipo de cr\u00e9dito con alguna entidad financiera. Es decir, si alguna vez solicitaste un cr\u00e9dito personal, alguna tarjeta de cr\u00e9dito o incluso sacaste un tel\u00e9fono a cr\u00e9dito seguramente est\u00e1s en bur\u00f3 de cr\u00e9dito.\u00a0<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\u00a1Ojo! Esto no significa nada malo para ti, al contrario todas estas acciones te ayudaron a construir tu historial crediticio y demostrar que sabes c\u00f3mo usar las herramientas financieras. Recuerda que toda tu actividad financiera (buena o mala) se ver\u00e1 reflejada en tu historial crediticio.<\/p>\r\n<p>Y entonces, \u00bfpara qu\u00e9 sirve el bur\u00f3 de cr\u00e9dito? Es una herramienta que le permite a otras instituciones conocerte mejor y saber c\u00f3mo te comportas financieramente, para determinar si te dan acceso a sus productos o no.\u00a0<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 tan malo es estar en bur\u00f3 de cr\u00e9dito?<\/h2>\r\n<p>\r\n\r\n<\/p>\r\n<p>Como te explicamos, el bur\u00f3 de cr\u00e9dito no es una lista negra simplemente es una lista de todos los que han pedido cr\u00e9ditos. Por ello estar en bur\u00f3 de cr\u00e9dito no significa algo negativo para ti, lo importante es conocer qu\u00e9 calificaci\u00f3n tienes en tu score crediticio.<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>Si has pagado todas tus deudas sin complicaciones, esto se ver\u00e1 reflejado en tu historial crediticio de forma positiva. Si por alguna raz\u00f3n tuviste problemas con alguna entidad financiera esto puede perjudicar tu historial y significar algo negativo para ti.<\/p>\r\n<h2>\u00bfCu\u00e1nto tiempo duras en el bur\u00f3 de cr\u00e9dito?<\/h2>\r\n<p>El tiempo que estar\u00e1s con esa calificaci\u00f3n negativa depender\u00e1 del monto de tu deuda.<\/p>\r\n<ul>\r\n<li>\u00a0Deudas menores o iguales a 25 UDIS, se eliminan despu\u00e9s de un a\u00f1o.<\/li>\r\n<li>\u00a0Deudas mayores a 25 UDIS y hasta 500 UDIS, se eliminan despu\u00e9s de dos a\u00f1os.<\/li>\r\n<li>\u00a0Deudas mayores a 500 UDIS y hasta 1000 UDIS, se eliminan despu\u00e9s de cuatro a\u00f1os.<\/li>\r\n<li>\u00a0Deudas mayores a 1000 UDIS, se eliminan despu\u00e9s de seis a\u00f1os siempre y cuando: sean menores a 400 mil UDIS, el cr\u00e9dito no se encuentre en proceso judicial y\/o no hayas cometido alg\u00fan fraude en tus cr\u00e9ditos.<\/li>\r\n<\/ul>\r\n<h2 data-sourcepos=\"23:1-23:38\">\u00bfC\u00f3mo ver mi historial crediticio?<\/h2>\r\n<p>Afortunadamente, existen varias maneras de consultar tu historial crediticio de forma gratuita. En M\u00e9xico puedes hacerlo a traves de\u00a0<a href=\"https:\/\/www.burodecredito.com.mx\/\" target=\"_blank\" rel=\"noopener\">Bur\u00f3 de Cr\u00e9dito<\/a>\u00a0o\u00a0<a href=\"https:\/\/www.circulodecredito.com.mx\/home\" target=\"_blank\" rel=\"noopener\">C\u00edrculo de Cr\u00e9dito.<\/a><\/p>\r\n<p>El proceso para revisar tu historial crediticio es sencillo. Por lo general, puedes ingresar a cualquiera de estas dos p\u00e1ginas, llenar su solicitud con tus datos personales y el c\u00f3digo de verificaci\u00f3n. As\u00ed podr\u00e1s recibir en tu correo electr\u00f3nico el reporte especial de tu historial de cr\u00e9dito para conocer qu\u00e9 deudas tienes reportadas y el estado actual de ellas.<\/p>\r\n<h2>Bur\u00f3 de cr\u00e9dito malo o bueno \u00bfc\u00f3mo saberlo?\u00a0<\/h2>\r\n<p>\r\n\r\n<\/p>\r\n<p>El score o puntaje crediticio es el n\u00famero que las entidades financieras eval\u00faan al momento en el que solicitas alg\u00fan producto (tarjetas de cr\u00e9dito, cr\u00e9ditos personales o cr\u00e9ditos hipotecarios). Se dividen en\u00a0 3 niveles:<\/p>\r\n<ul>\r\n<li><strong>Negativo. <\/strong>Se considera un bur\u00f3 de cr\u00e9dito malo cuando tu score crediticio est\u00e1 por debajo de los 400 puntos.<\/li>\r\n<li><strong>M\u00ednimo<\/strong>.\u00a0 El puntaje con el que las instituciones financieras a\u00fan te pueden considerar para sus productos va de 600 a 700.\u00a0<\/li>\r\n<li><strong>Superior<\/strong>. Si tu puntaje crediticio est\u00e1 entre 750 puntos y los 850 puntos eres visto como alguien confiable y con solvencia econ\u00f3mica.\u00a0<\/li>\r\n<\/ul>\r\n<h3>\u00bfSe puede salir de bur\u00f3?\u00a0<\/h3>\r\n<p><\/p>\r\n<p>Como ya mencionamos, tu historial crediticio no se puede borrar pero si se puede mejorar. En el caso de que te preocupe alguna deuda que terminaste de pagar apenas o con la que tuviste complicaciones hace algunos a\u00f1os \u00a1tranqu\u00edlizate!\u00a0Mientras tu deuda est\u00e9 pagada esto no perjudicar\u00e1 a tu historial, solo te recomendamos que a partir de ahora cuides tu comportamiento de pago.\u00a0\u00a0<\/p>\r\n<p><a href=\"https:\/\/www.creditas.mx\/prestamo\/garantia-auto?utm_medium=blog&amp;utm_source=blog&amp;utm_content=buro-de-credito-como-mejorarlo&amp;utm_campaign=[mx][ar]-blog-garantia\"><img decoding=\"async\" class=\"lazyload alignnone wp-image-4353 size-full\" title=\"como mejorar tu historial crediticio\" src=\"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2.jpg\" data-orig-src=\"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2.jpg\" alt=\"buro de cr\u00e9dito como mejorarlo\" width=\"800\" height=\"400\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27800%27%20height%3D%27400%27%20viewBox%3D%270%200%20800%20400%27%3E%3Crect%20width%3D%27800%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2-200x100.jpg 200w, https:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2-300x150.jpg 300w, https:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2-400x200.jpg 400w, https:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2-600x300.jpg 600w, https:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2-768x384.jpg 768w, https:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2024\/07\/CRM_BLOG_ABRIL_04-2.jpg 800w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\r\n<h2><strong>\u00bfC\u00f3mo mejorar tu historial crediticio?<\/strong><\/h2>\r\n<p><strong>Sigue estas recomendaciones financieras para mejorar tu historial crediticio.\u00a0<\/strong><\/p>\r\n<ol data-sourcepos=\"41:1-50:0\">\r\n<li data-sourcepos=\"41:1-42:3\"><strong>Paga tus deudas a tiempo:<\/strong>\u00a0Este es el factor m\u00e1s importante. Cubre mes a mes tus deudas ya que los pagos atrasados afectan negativamente tu historial.<\/li>\r\n<li data-sourcepos=\"43:1-44:3\"><strong>Mant\u00e9n un bajo nivel de endeudamiento:<\/strong>\u00a0No utilices todo el cr\u00e9dito disponible en tus tarjetas, intenta s\u00f3lo utilizar el 50% de tu l\u00ednea de cr\u00e9dito.<\/li>\r\n<li data-sourcepos=\"45:1-46:3\"><strong>Diversifica tus cr\u00e9ditos:<\/strong>\u00a0Tener diferentes tipos de cr\u00e9dito (tarjeta, pr\u00e9stamo, etc.) y manejarlos bien puede ser positivo. Evita pedir dos cr\u00e9ditos del mismo tipo al mismo tiempo.<\/li>\r\n<li data-sourcepos=\"47:1-48:3\"><strong>Revisa tu historial peri\u00f3dicamente:\u00a0<\/strong>Aseg\u00farate de que la informaci\u00f3n sobre tus deudas y cr\u00e9ditos activos sea correcta y si detectasposibles errores est\u00e1s a tiempo de impugnarlos. Revisa tu <a href=\"https:\/\/www.creditas.mx\/exponencial\/como-saber-mi-score-crediticio\/\">score crediticio<\/a>.<\/li>\r\n<li data-sourcepos=\"49:1-50:0\"><strong>Evita solicitar cr\u00e9ditos en exceso:<\/strong>\u00a0Cada solicitud queda registrada y puede dar la impresi\u00f3n de que tienes problemas financieros.<\/li>\r\n<li data-sourcepos=\"49:1-50:0\"><strong>Conoce tu capacidad de pago<\/strong>. Si pides un cr\u00e9dito calcula cu\u00e1nto de tus ingresos puedes destinar para pagarlo, generalmente destinarle menos del 30% de tu salario te permitir\u00e1 cubrirlo sin problemas.<\/li>\r\n<\/ol>\r\n<p>Si te encuentras en los niveles de m\u00ednimo o negativo, probablemente se deba a que tienes deudas sin pagar o atrasos en los pagos de tus cr\u00e9ditos. La mejor forma de mejorar tu historial crediticio y eliminar la mala percepci\u00f3n en tu bur\u00f3 de cr\u00e9dito es poni\u00e9ndote al corriente de esos cr\u00e9ditos.\u00a0<\/p>\r\n<p>Recuerda que en el caso de las tarjetas de cr\u00e9dito lo mejor es pagar el &#8220;pago total para no generar intereses&#8221; y no el pago m\u00ednimo, de lo contrario podr\u00edas estar perjudicando tu historial crediticio.\u00a0 En caso de que tengas problemas para pagar tus deudas, te recomendamos leer: <a title=\"4 opciones para pagar tus deudas.\" href=\"https:\/\/www.creditas.mx\/exponencial\/4-opciones-para-que-pagues-tus-deudas\/\">4 opciones para pagar tus deudas.<\/a><\/p>\r\n<p><!-- \/wp:paragraph -->\r\n\r\n<!-- wp:paragraph --><\/p>\r\n<h2>\u00bfC\u00f3mo crear un buen historial crediticio desde cero?<\/h2>\r\n<p>Construir tu historial crediticio es tan importante como construir tu experiencia labora;, as\u00ed como en el trabajo\u00a0 empiezas con algo sencillo y cuando adquieres experiencia y nuevas habilidades eres capaz de pedir posiciones m\u00e1s altas, empezar con cr\u00e9ditos sencillos y tener un buen comportamiento te permitir\u00e1 acceder a m\u00e1s productos crediticios y montos m\u00e1s altos<\/p>\r\n<p>Si a\u00fan no has tenido ning\u00fan producto financiero, te dejamos algunas recomendaciones:<\/p>\r\n<ul>\r\n<li aria-level=\"1\"><strong>Abre tu cuenta de n\u00f3mina o una cuenta personal.<\/strong>\u00a0Realiza dep\u00f3sitos en cuentas de ahorro, n\u00f3mina o personales para que las instituciones financieras conozcan tu nivel de ingresos. Aunque esto no aparece en tu historial de cr\u00e9dito, puede ayudar a que estas instituciones te den tu primer pr\u00e9stamo.\u00a0<\/li>\r\n<li aria-level=\"1\"><a href=\"https:\/\/www.creditas.mx\/prestamo\/garantia-auto?utm_medium=blog&amp;utm_source=blog&amp;utm_content=articulo&amp;utm_campaign=[mx][ar]-mejor-historial-crediticio\"><strong>Contrata alg\u00fan cr\u00e9dito sencillo.<\/strong>\u00a0<\/a>Puedes optar por un cr\u00e9dito de pagos fijos, como sacar un tel\u00e9fono a meses con tu proveedor de telefon\u00eda, procura elegir una deuda que est\u00e9 en tu capacidad de pago para no desajustar tus finanzas personales.\u00a0<\/li>\r\n<li aria-level=\"1\"><strong>Si tu banco te ofrece una tarjeta de cr\u00e9dito, ac\u00e9ptala.<\/strong>\u00a0 Muchas instituciones suelen ofrecerte tarjetas de cr\u00e9dito cuando llevas tiempo con tu cuenta de n\u00f3mina. Tu primera tarjeta tendr\u00e1 un l\u00edmite de cr\u00e9dito bajo, pero puedes usarla para construir tu historial crediticio.<\/li>\r\n<\/ul>\r\n<p>\u00a1Si ya te ofrecieron tu tarjeta de cr\u00e9dito ahora toca ser responsable!<\/p>\r\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Aparecer el bur\u00f3 de cr\u00e9dito es para muchos una causa de estr\u00e9s y preocupaci\u00f3n. Te explicamos qu\u00e9 significa en realidad y qu\u00e9 tan malo es estar en bur\u00f3 de cr\u00e9dito, as\u00ed como algunos tips para mejorar tu historial crediticio. <\/p>\n","protected":false},"author":17,"featured_media":2556,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[49],"tags":[65,72],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo? - Creditas<\/title>\n<meta name=\"description\" content=\"Tener un historial en buro de cr\u00e9dito malo podr\u00eda afectarte al momento de pedir m\u00e1s cr\u00e9ditos, te decimos c\u00f3mo solucionarlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo? - Creditas\" \/>\n<meta property=\"og:description\" content=\"Tener un historial en buro de cr\u00e9dito malo podr\u00eda afectarte al momento de pedir m\u00e1s cr\u00e9ditos, te decimos c\u00f3mo solucionarlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Creditas\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-17T17:46:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T17:41:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2022\/08\/GettyImages-1318181089.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Axel S Marin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Axel S Marin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/\",\"url\":\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/\",\"name\":\"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo? - Creditas\",\"isPartOf\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#website\"},\"datePublished\":\"2022-08-17T17:46:16+00:00\",\"dateModified\":\"2026-07-28T17:41:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625\"},\"description\":\"Tener un historial en buro de cr\u00e9dito malo podr\u00eda afectarte al momento de pedir m\u00e1s cr\u00e9ditos, te decimos c\u00f3mo solucionarlo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.creditas.mx\/exponencial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#website\",\"url\":\"https:\/\/www.creditas.mx\/exponencial\/\",\"name\":\"Creditas\",\"description\":\"Blog de Educaci\u00f3n Financiera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.creditas.mx\/exponencial\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625\",\"name\":\"Axel S Marin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g\",\"caption\":\"Axel S Marin\"},\"url\":\"https:\/\/www.creditas.mx\/exponencial\/author\/axel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo? - Creditas","description":"Tener un historial en buro de cr\u00e9dito malo podr\u00eda afectarte al momento de pedir m\u00e1s cr\u00e9ditos, te decimos c\u00f3mo solucionarlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo? - Creditas","og_description":"Tener un historial en buro de cr\u00e9dito malo podr\u00eda afectarte al momento de pedir m\u00e1s cr\u00e9ditos, te decimos c\u00f3mo solucionarlo.","og_url":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/","og_site_name":"Creditas","article_published_time":"2022-08-17T17:46:16+00:00","article_modified_time":"2026-07-28T17:41:24+00:00","og_image":[{"width":2121,"height":1414,"url":"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2022\/08\/GettyImages-1318181089.jpg","type":"image\/jpeg"}],"author":"Axel S Marin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Axel S Marin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/","url":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/","name":"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo? - Creditas","isPartOf":{"@id":"https:\/\/www.creditas.mx\/exponencial\/#website"},"datePublished":"2022-08-17T17:46:16+00:00","dateModified":"2026-07-28T17:41:24+00:00","author":{"@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625"},"description":"Tener un historial en buro de cr\u00e9dito malo podr\u00eda afectarte al momento de pedir m\u00e1s cr\u00e9ditos, te decimos c\u00f3mo solucionarlo.","breadcrumb":{"@id":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.creditas.mx\/exponencial\/buro-de-credito-malo-como-mejorarlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.creditas.mx\/exponencial\/"},{"@type":"ListItem","position":2,"name":"\u00bfEstar en bur\u00f3 de cr\u00e9dito es algo malo?"}]},{"@type":"WebSite","@id":"https:\/\/www.creditas.mx\/exponencial\/#website","url":"https:\/\/www.creditas.mx\/exponencial\/","name":"Creditas","description":"Blog de Educaci\u00f3n Financiera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.creditas.mx\/exponencial\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Person","@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625","name":"Axel S Marin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g","caption":"Axel S Marin"},"url":"https:\/\/www.creditas.mx\/exponencial\/author\/axel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts\/2509"}],"collection":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/comments?post=2509"}],"version-history":[{"count":0,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts\/2509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/media\/2556"}],"wp:attachment":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/media?parent=2509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/categories?post=2509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/tags?post=2509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}