{"id":2471,"date":"2022-07-01T07:09:57","date_gmt":"2022-07-01T12:09:57","guid":{"rendered":"https:\/\/www.creditas.mx\/exponencial\/?p=2471"},"modified":"2022-08-11T12:10:47","modified_gmt":"2022-08-11T17:10:47","slug":"como-afecta-la-nueva-tasa-de-interes-a-tus-creditos","status":"publish","type":"post","link":"https:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/","title":{"rendered":"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos?"},"content":{"rendered":"<p>Durante la pasada semana el Banco Nacional de M\u00e9xico (BANXICO) public\u00f3 la nueva tasa de inter\u00e9s de 7.75% . Esta decisi\u00f3n ha sido hist\u00f3rica, pues es el alza m\u00e1s alta que ha hecho la instituci\u00f3n en los \u00faltimos 25 a\u00f1os, hoy te explicamos c\u00f3mo puede afectar a tus cr\u00e9ditos y pr\u00e9stamos activos y qu\u00e9 deber\u00edas hacer si eres uno de los afectados.<\/p>\n<h3>\u00bfQu\u00e9 es la tasa de inter\u00e9s?<\/h3>\n<p>La tasa de inter\u00e9s es la cifra que indica el costo por el dinero que te prestan los bancos u otras instituciones financieras, ya sea mediante un pr\u00e9stamo personal, de n\u00f3mina; un cr\u00e9dito para comprar tu auto, tu casa u otros cr\u00e9ditos personales (como las tarjetas de cr\u00e9dito, por ejemplo).<\/p>\n<p>Esta tasa de inter\u00e9s varia dependiendo de los productos y de las instituciones financieras, de ah\u00ed que algunos productos siempre te convengan m\u00e1s que otros. Cada banco determina cu\u00e1l es el costo de prestarte ese dinero y los intereses que te cobrar\u00e1n.<\/p>\n<h3>\u00bfPor qu\u00e9 se subi\u00f3 la tasa de inter\u00e9s?<\/h3>\n<p>Seguramente has notado que desde principios de a\u00f1o ha habido un aumento en el costo de diversos productos alimenticios y ciertos servicios.\u00a0 Esto es debido a la inflaci\u00f3n, que desde noviembre ha alcanzado niveles muy altos y no ha bajado tanto como en otros a\u00f1os.\u00a0 En enero iniciamos con una inflaci\u00f3n del 8.37% y.para la primera quincena de junio se ubicaba en 7.88%.<\/p>\n<p>Cuando los bancos nos ofrecen tasas de inter\u00e9s bajas solemos aceptar el dinero que nos ofrecen &#8220;pues nos cuesta menos&#8221; y se vuelven m\u00e1s sencillos de pagar, al no bajar la inflaci\u00f3n el Banco de M\u00e9xico tiene que tomar acciones para apreciar m\u00e1s el dinero, subir la tasa de inter\u00e9s es una forma de volver los cr\u00e9ditos m\u00e1s caros y desincentivar el consumo de estos productos como soluci\u00f3n para frenar la inflaci\u00f3n.<\/p>\n<h2>\u00bfC\u00f3mo afecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos?<\/h2>\n<p>El anuncio del aumento en la tasa de inter\u00e9s s\u00f3lo te afecta si actualmente tienes alg\u00fan cr\u00e9dito de auto, casa, o alg\u00fan pr\u00e9stamo personal a <strong>tasa variable\u00a0<\/strong>pues tus pagos mensuales podr\u00edan incrementar pr\u00f3ximamente.\u00a0 Algunos cr\u00e9ditos a tasa variable pueden ser:<\/p>\n<ul>\n<li><strong>El monto que no alcanzaste a pagar en tu tarjeta de cr\u00e9dito<\/strong> el mes pasado, cuando no cubres el total de tu deuda este monto genera diversos intereses que se acumulan mes a mes, salvo que sea una deuda a meses sin intereses.<\/li>\n<li><strong>Cr\u00e9ditos hipotecarios,<\/strong> algunas instituciones te ofrecen cr\u00e9ditos para adquirir tu casa con tasa variable en las que tu pago mensual depende del movimiento del sector financiero.<\/li>\n<li><strong>Cr\u00e9ditos departamentales,<\/strong> algunas tarjetas y cr\u00e9ditos ofrecidos por tiendas departamentales consideran una tasa de inter\u00e9s variable.<\/li>\n<\/ul>\n<p>Si tu tasa de inter\u00e9s es fija este anuncio de Banxico no tiene ninguna afectaci\u00f3n para ti, siempre y cuando te mantengas al corriente de tus pagos mensuales.<\/p>\n<p>En caso de que no sepas qu\u00e9 tipo de tasa de inter\u00e9s maneja tu cr\u00e9dito (si fija o variable) te recomendamos revisar las condiciones en tu contrato o acercarte con tu asesor financiero, lo mejor es salir de dudas para saber si te afecta o no y tener la informaci\u00f3n necesaria para saber c\u00f3mo actuar.<\/p>\n<h3>Tips para que la nueva tasa de inter\u00e9s no te afecte<\/h3>\n<p><strong>Salda tus deudas. <\/strong><\/p>\n<p>Si tienes la oportunidad de saldar tus deudas hazlo, sobre todo si est\u00e1n sujetas a una tasa de inter\u00e9s alta o son de inter\u00e9s variable. Una buena opci\u00f3n puede ser buscar cr\u00e9ditos con tasas m\u00e1s bajas para refinanciar tu deuda alta.<\/p>\n<p>Otra opci\u00f3n que puede ayudarte es aporta al capital de tu deuda, para reducir el monto financiado y la cantidad de inter\u00e9s que est\u00e1s pagando actualmente. Aprovecha cualquier ingreso extra que tengas y ap\u00f3rtalo a tu cr\u00e9dito. Ac\u00e1 te compartimos algunas <a href=\"https:\/\/www.creditas.mx\/exponencial\/4-opciones-para-que-pagues-tus-deudas\/\">opciones para liquidar tus deudas. <\/a><\/p>\n<p><strong>No te atrases en tus pagos.<\/strong><\/p>\n<p>S\u00e9 lo m\u00e1s puntual que puedas con tus pagos de cr\u00e9ditos o pr\u00e9stamos para evitar sanciones monetarias o generar aumentos por el inter\u00e9s.<\/p>\n<p>Si usas tarjetas de cr\u00e9dito frecuentemente cuida de no dejar un monto sin pagar en ellas, no cubras s\u00f3lo el pago m\u00ednimo pues esto generar\u00e1 intereses para tu siguiente mes. Lo mejor que puedes hacer es convertirte en <em>totalero<\/em>, es decir, pagar el total de tu deuda mes a mes.<\/p>\n<p><strong>Ahorra en instrumentos de inversi\u00f3n.<\/strong><\/p>\n<p>La buena noticia de este aumento en las tasas de inter\u00e9s es que \u00a1tu ahorro valdr\u00e1 m\u00e1s! Raz\u00f3n de sobra para comenzar a modificar tus h\u00e1bitos financieros y destinar parte de tus recursos a la creaci\u00f3n de un fondo de ahorro.<\/p>\n<p>Utilizar tus ahorros para comenzar alguna inversi\u00f3n (como <a href=\"https:\/\/www.cetesdirecto.com\/sites\/portal\/inicio\">CETES<\/a>) tambi\u00e9n puede ayudarte a conservar el valor de tu dinero, as\u00ed no s\u00f3lo estar\u00e1s preparado para cualquier eventualidad sino que tambi\u00e9n podr\u00e1s ganarle un poco a la inflaci\u00f3n y hacer que tu dinero siga creciendo.<\/p>\n<p>Ya sea que la nueva tasa de inter\u00e9s te afecte o no, este es el momento perfecto para organizar mejor tus finanzas y cambiar tus h\u00e1bitos financieros. \u00a1Estamos seguros de que puedes lograrlo! \ud83d\ude0e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te explicamos en qu\u00e9 consiste el nuevo aumento a las tasas de inter\u00e9s de Banxico y c\u00f3mo puede afectarle a tus cr\u00e9ditos personales. <\/p>\n","protected":false},"author":17,"featured_media":2472,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[49],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos? - Creditas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos? - Creditas\" \/>\n<meta property=\"og:description\" content=\"Te explicamos en qu\u00e9 consiste el nuevo aumento a las tasas de inter\u00e9s de Banxico y c\u00f3mo puede afectarle a tus cr\u00e9ditos personales.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/\" \/>\n<meta property=\"og:site_name\" content=\"Creditas\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-01T12:09:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-11T17:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2022\/06\/GettyImages-1150687416.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2120\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Axel S Marin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Axel S Marin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/\",\"url\":\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/\",\"name\":\"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos? - Creditas\",\"isPartOf\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#website\"},\"datePublished\":\"2022-07-01T12:09:57+00:00\",\"dateModified\":\"2022-08-11T17:10:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.creditas.mx\/exponencial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#website\",\"url\":\"https:\/\/www.creditas.mx\/exponencial\/\",\"name\":\"Creditas\",\"description\":\"Blog de Educaci\u00f3n Financiera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.creditas.mx\/exponencial\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625\",\"name\":\"Axel S Marin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g\",\"caption\":\"Axel S Marin\"},\"url\":\"https:\/\/www.creditas.mx\/exponencial\/author\/axel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos? - Creditas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos? - Creditas","og_description":"Te explicamos en qu\u00e9 consiste el nuevo aumento a las tasas de inter\u00e9s de Banxico y c\u00f3mo puede afectarle a tus cr\u00e9ditos personales.","og_url":"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/","og_site_name":"Creditas","article_published_time":"2022-07-01T12:09:57+00:00","article_modified_time":"2022-08-11T17:10:47+00:00","og_image":[{"width":2120,"height":1414,"url":"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2022\/06\/GettyImages-1150687416.jpg","type":"image\/jpeg"}],"author":"Axel S Marin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Axel S Marin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/","url":"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/","name":"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos? - Creditas","isPartOf":{"@id":"https:\/\/www.creditas.mx\/exponencial\/#website"},"datePublished":"2022-07-01T12:09:57+00:00","dateModified":"2022-08-11T17:10:47+00:00","author":{"@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625"},"breadcrumb":{"@id":"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.creditas.mx\/exponencial\/como-afecta-la-nueva-tasa-de-interes-a-tus-creditos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.creditas.mx\/exponencial\/"},{"@type":"ListItem","position":2,"name":"\u00bfAfecta la nueva tasa de inter\u00e9s a tus cr\u00e9ditos?"}]},{"@type":"WebSite","@id":"https:\/\/www.creditas.mx\/exponencial\/#website","url":"https:\/\/www.creditas.mx\/exponencial\/","name":"Creditas","description":"Blog de Educaci\u00f3n Financiera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.creditas.mx\/exponencial\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Person","@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625","name":"Axel S Marin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g","caption":"Axel S Marin"},"url":"https:\/\/www.creditas.mx\/exponencial\/author\/axel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts\/2471"}],"collection":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/comments?post=2471"}],"version-history":[{"count":0,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts\/2471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/media\/2472"}],"wp:attachment":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/media?parent=2471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/categories?post=2471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/tags?post=2471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}