{"id":2143,"date":"2021-12-23T09:45:00","date_gmt":"2021-12-23T15:45:00","guid":{"rendered":"https:\/\/www.creditas.mx\/exponencial\/?p=2143"},"modified":"2024-04-24T16:11:02","modified_gmt":"2024-04-24T22:11:02","slug":"prestamos-con-garantia-8-mitos-y-verdades","status":"publish","type":"post","link":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/","title":{"rendered":"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades."},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Seguro has escuchado recientemente sobre los pr\u00e9stamos con garant\u00eda, quiz\u00e1 es un concepto completamente nuevo para ti, por eso queremos ayudarte a entender qu\u00e9 son los pr\u00e9stamos con garant\u00eda a trav\u00e9s de los mitos m\u00e1s comunes alrededor de ellos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los pr\u00e9stamos con garant\u00eda son un producto todav\u00eda nuevo y un tanto desconocido para nosotros los mexicanos, s\u00f3lo el 30% de los cr\u00e9ditos en el pa\u00eds son de este tipo, mientras que en pa\u00edses como EE.UU Este tipo de cr\u00e9ditos representa hasta el 85% de todos los cr\u00e9ditos otorgados.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si quieres leer m\u00e1s a detalle sobre <a href=\"https:\/\/www.creditas.mx\/exponencial\/que-es-y-como-funciona-el-prestamo-con-garantia\/\">c\u00f3mo funcionan los pr\u00e9stamos con garant\u00eda puedes ir aqu\u00ed.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">A continuaci\u00f3n te contamos qu\u00e9 es un mito y qu\u00e9 es realidad sobre los pr\u00e9stamos con garant\u00eda:<\/span><\/p>\n<h2><span style=\"font-weight: 400;\"><strong>1) Para obtener un pr\u00e9stamo con garant\u00eda, debo colocar un bien o activo como garant\u00eda de pago en mi contrato.<\/strong> <\/span><b>VERDAD<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">El pr\u00e9stamo con garant\u00eda es una modalidad en la que ofreces un bien a tu nombre a la instituci\u00f3n que te otorga el cr\u00e9dito, m\u00edralo como un \u201caval\u201d para obtener el cr\u00e9dito. La garant\u00eda se coloca en el contrato de pr\u00e9stamo, y en caso de incumplimiento, puede venderse para liquidar la deuda. Las instituciones crediticias pueden aceptar diversos bienes como garant\u00eda, como por ejemplo: una propiedad, veh\u00edculo, joyas e incluso el mismo salario del prestatario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Debido a que se ofrece una garant\u00eda para el pr\u00e9stamo, la transacci\u00f3n se considera menos riesgosa. De esta forma, el acreedor puede ofrecer el cr\u00e9dito a tasas de inter\u00e9s m\u00e1s bajas y con plazos m\u00e1s largos para pagar de vuelta la suma prestada m\u00e1s intereses y comisiones. Lo m\u00e1s importante es que no dejar\u00e1s de usar tus bienes mientras est\u00e1s en el proceso de pagar el cr\u00e9dito.\u00a0<\/span><\/p>\n<h3><strong>2) Debo demostrar ingresos para obtener el pr\u00e9stamo, incluso si son<\/strong><strong> pr\u00e9stamos con garant\u00eda.\u00a0 <\/strong><b>VERDAD<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">S\u00ed. A pesar de que se trata de una transacci\u00f3n en la que un bien se coloca como garant\u00eda, es importante que haya prueba de ingresos. Estas son precauciones adicionales que toman los acreedores para evitar incumplimientos durante la operaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este proceso tambi\u00e9n ayuda a identificar c\u00f3mo est\u00e1n tus finanzas actualmente, si puedes pagar el pr\u00e9stamo, y ayudar\u00e1 a definir qu\u00e9 monto te prestar\u00e1n, la tasa de inter\u00e9s que obtendr\u00e1s y el plazo de pago m\u00e1s conveniente para ti.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, es una forma de protegerte ante un sobre-endeudamiento. Las instituciones tienen que entender tu capacidad de pago y brindarte un pr\u00e9stamo enfocado en ello.\u00a0<\/span><\/p>\n<h4><strong>3) El bien pasa al nombre de la empresa que presta el dinero. <\/strong><b>MITO<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Esta afirmaci\u00f3n es un mito. Incluso poniendo el bien en garant\u00eda, sigue siendo tuyo. Lo que ocurre en este proceso es que el bien, ya sea un autom\u00f3vil o una propiedad, se enajena temporalmente a la instituci\u00f3n que ofreci\u00f3 el cr\u00e9dito pero el financista es quien tendr\u00e1 la reserva de dominio hasta que se pague la deuda.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En otras palabras, el bien permanecer\u00e1 en tu posesi\u00f3n, pero la propiedad (posesi\u00f3n indirecta) permanece con la empresa que proporcion\u00f3 el pr\u00e9stamo. Al liquidar el cr\u00e9dito, esta informaci\u00f3n puede eliminarse del documento del bien.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\"><strong>4) Para obtener el pr\u00e9stamo con garant\u00eda debo hacer alg\u00fan anticipo<\/strong>. <\/span><b>MITO<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u00a1Mucha atenci\u00f3n, si recibes este tipo de solicitudes podr\u00eda tratarse de una estafa!. La CONDUSEF recomienda evitar entidades que soliciten anticipos para la adquisici\u00f3n de pr\u00e9stamos. Los \u201ccr\u00e9ditos express\u201d son un tipo de fraude que consiste en la solicitud de anticipos con el pretexto de apartar el pr\u00e9stamo, gestionarlo, pagar gastos de apertura u otros. Por lo general, una vez se realiza el dep\u00f3sito, no recibes el pr\u00e9stamo solicitado, y para el momento en que te das cuenta de que fuiste enga\u00f1ada ya no puedes localizar al \u201cprestamista\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por eso, debes ejercer cautela. Antes de solicitar pr\u00e9stamos, comun\u00edcate con la empresa que brinda el cr\u00e9dito. Es normal que te soliciten datos, pues deben analizar tu perfil crediticio, despu\u00e9s de todos los procedimientos de documentaci\u00f3n, an\u00e1lisis de cr\u00e9dito y validaci\u00f3n de documentos, comenzar\u00e1 el proceso de formalizaci\u00f3n del pedido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En ese momento, el prestatario recibir\u00e1 un documento (Nota de Cr\u00e9dito Bancario). Con el contrato firmado, el siguiente paso es recibir el monto del cr\u00e9dito solicitado. Solo despu\u00e9s de estos procesos se empiezan a pagar las cuotas del pr\u00e9stamo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por esa raz\u00f3n, el mejor consejo es estar atentos y buscar cr\u00e9ditos con instituciones financieras reguladas.<\/span><\/p>\n<h3><strong>5) Mi historial crediticio (sea negativo o no) influye para conseguir el pr\u00e9stamo. <\/strong><b>VERDAD<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">No permitas que te tome por sorpresa tener historial crediticio negativo en el mercado. Los registros desactualizados y la falta de informaci\u00f3n pueden contribuir a estos resultados, adem\u00e1s, por supuesto, del impago de la deuda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin duda, tu historial en el mercado indica tu situaci\u00f3n financiera, si est\u00e1s en default. Y eso influye a la hora de conseguir un pr\u00e9stamo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por eso es muy importante monitorear tu historial, y revisar si tienes alguna deuda o si te afect\u00f3 negativamente una cuenta vencida &#8211; una que quiz\u00e1s ni siquiera recordabas que exist\u00eda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ser\u00e1 m\u00e1s dif\u00edcil obtener aprobaci\u00f3n para cr\u00e9dito si al hacer una b\u00fasqueda con tu nombre encuentran un perfil negativo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, no te desanimes, las instituciones que ofrecen pr\u00e9stamos con garant\u00eda al tener un riesgo operativo menor suelen ser m\u00e1s flexibles que la banca tradicional al ofrecer pr\u00e9stamos personales, por ejemplo.<\/span><\/p>\n<h4><strong>6) Es posible solicitar cualquier cantidad. <\/strong><b>MITO<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Como con otro tipo de pr\u00e9stamos, la garant\u00eda tiene un monto m\u00ednimo y m\u00e1ximo que se puede solicitar, este var\u00eda seg\u00fan la empresa que pondr\u00e1 a disposici\u00f3n el monto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, existen otros factores que influyen en el proceso. La cantidad solicitada tambi\u00e9n puede variar seg\u00fan la capacidad de pago del acreedor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el caso de Creditas, por ejemplo, para pr\u00e9stamos con garant\u00eda de auto, la empresa puede ceder hasta el 80% del valor del auto. Esto depender\u00e1 del modelo, a\u00f1o y perfil del veh\u00edculo. En el caso de la garant\u00eda de propiedad, es posible solicitar hasta el 50% del valor de la propiedad colocada como garant\u00eda.\u00a0<\/span><\/p>\n<h3><strong>7) El bien se puede tomar en caso de incumplimiento del pr\u00e9stamo. <\/strong><b>VERDAD<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">En caso de impago de la deuda, el bien colocado como garant\u00eda s\u00ed puede ser tomado. Sin embargo, es importante se\u00f1alar que el objetivo de la empresa que ofrece el cr\u00e9dito no es tomar el bien colocado como garant\u00eda. Funciona solo como una certificaci\u00f3n importante de que se reembolsar\u00e1 el pr\u00e9stamo. Es por ello que los intereses y plazos de esta modalidad son mejores, ya que el activo colocado como garant\u00eda brinda mayor seguridad de que el pr\u00e9stamo se pagar\u00e1 de alguna manera.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La propiedad del bien la tendr\u00e1 la instituci\u00f3n hasta el pago final del pr\u00e9stamo. Si el prestatario est\u00e1 en mora, el bien ir\u00e1 al banco, o qui\u00e9n sea el financista.<\/span><\/p>\n<h3><strong>8) Es posible obtener el pr\u00e9stamo mediante la colocaci\u00f3n de un garante. <\/strong><b>VERDAD<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">S\u00ed, es posible obtener un pr\u00e9stamo colocando un garante como garant\u00eda en la operaci\u00f3n. En el caso de un pr\u00e9stamo con garant\u00eda, el garante debe ser una persona de primer grado &#8211; padre, madre o c\u00f3nyuge &#8211; que se comprometa a sumar los ingresos y \/ o ser responsable de pagar las cuotas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para las empresas que brindan cr\u00e9dito, el garante es una especie de garant\u00eda de que se pagar\u00e1 la deuda. Es importante recordar que el activo debe estar a nombre de la persona que solicitar\u00e1 el pr\u00e9stamo. El garante s\u00f3lo se sumar\u00e1 al proceso como respaldo.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00bfTienes m\u00e1s dudas sobre los pr\u00e9stamos con garant\u00eda? Conoce <a href=\"https:\/\/www.creditas.mx\/prestamo\/garantia-auto?utm_medium=blog&amp;utm_source=blog&amp;utm_content=articulo&amp;utm_campaign=[mx][ar]-pr\u00e9stamos-con-garant\u00eda\">nuestras soluciones<\/a> y habla con nuestros consultores para resolverlas.<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Existe mucha confusi\u00f3n sobre c\u00f3mo funcionan los pr\u00e9stamos con garant\u00eda pero no te preocupes, aqu\u00ed te respondemos tus principales dudas.<\/p>\n","protected":false},"author":17,"featured_media":1997,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[49],"tags":[6,53],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades. - Creditas<\/title>\n<meta name=\"description\" content=\"Todas tus dudas sobre los pr\u00e9stamos con garant\u00eda est\u00e1n resueltas aqu\u00ed. Te explicamos los mitos m\u00e1s comunes de estos pr\u00e9stamos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades. - Creditas\" \/>\n<meta property=\"og:description\" content=\"Todas tus dudas sobre los pr\u00e9stamos con garant\u00eda est\u00e1n resueltas aqu\u00ed. Te explicamos los mitos m\u00e1s comunes de estos pr\u00e9stamos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/\" \/>\n<meta property=\"og:site_name\" content=\"Creditas\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T15:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T22:11:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2020\/12\/post-image-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1270\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Axel S Marin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Axel S Marin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/\",\"url\":\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/\",\"name\":\"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades. - Creditas\",\"isPartOf\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#website\"},\"datePublished\":\"2021-12-23T15:45:00+00:00\",\"dateModified\":\"2024-04-24T22:11:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625\"},\"description\":\"Todas tus dudas sobre los pr\u00e9stamos con garant\u00eda est\u00e1n resueltas aqu\u00ed. Te explicamos los mitos m\u00e1s comunes de estos pr\u00e9stamos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.creditas.mx\/exponencial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#website\",\"url\":\"https:\/\/www.creditas.mx\/exponencial\/\",\"name\":\"Creditas\",\"description\":\"Blog de Educaci\u00f3n Financiera\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.creditas.mx\/exponencial\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625\",\"name\":\"Axel S Marin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g\",\"caption\":\"Axel S Marin\"},\"url\":\"https:\/\/www.creditas.mx\/exponencial\/author\/axel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades. - Creditas","description":"Todas tus dudas sobre los pr\u00e9stamos con garant\u00eda est\u00e1n resueltas aqu\u00ed. Te explicamos los mitos m\u00e1s comunes de estos pr\u00e9stamos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/","og_locale":"es_MX","og_type":"article","og_title":"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades. - Creditas","og_description":"Todas tus dudas sobre los pr\u00e9stamos con garant\u00eda est\u00e1n resueltas aqu\u00ed. Te explicamos los mitos m\u00e1s comunes de estos pr\u00e9stamos.","og_url":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/","og_site_name":"Creditas","article_published_time":"2021-12-23T15:45:00+00:00","article_modified_time":"2024-04-24T22:11:02+00:00","og_image":[{"width":1270,"height":700,"url":"http:\/\/www.creditas.mx\/exponencial\/wp-content\/uploads\/2020\/12\/post-image-03.jpg","type":"image\/jpeg"}],"author":"Axel S Marin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Axel S Marin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/","url":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/","name":"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades. - Creditas","isPartOf":{"@id":"https:\/\/www.creditas.mx\/exponencial\/#website"},"datePublished":"2021-12-23T15:45:00+00:00","dateModified":"2024-04-24T22:11:02+00:00","author":{"@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625"},"description":"Todas tus dudas sobre los pr\u00e9stamos con garant\u00eda est\u00e1n resueltas aqu\u00ed. Te explicamos los mitos m\u00e1s comunes de estos pr\u00e9stamos.","breadcrumb":{"@id":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.creditas.mx\/exponencial\/prestamos-con-garantia-8-mitos-y-verdades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.creditas.mx\/exponencial\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9stamos con garant\u00eda: 8 mitos y verdades."}]},{"@type":"WebSite","@id":"https:\/\/www.creditas.mx\/exponencial\/#website","url":"https:\/\/www.creditas.mx\/exponencial\/","name":"Creditas","description":"Blog de Educaci\u00f3n Financiera","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.creditas.mx\/exponencial\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Person","@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/9d9585b2268640223694ac30e5d26625","name":"Axel S Marin","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.creditas.mx\/exponencial\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59105e5797efc0554e8e846eda4fd0d5?s=96&d=blank&r=g","caption":"Axel S Marin"},"url":"https:\/\/www.creditas.mx\/exponencial\/author\/axel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts\/2143"}],"collection":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/comments?post=2143"}],"version-history":[{"count":0,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/posts\/2143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/media\/1997"}],"wp:attachment":[{"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.creditas.mx\/exponencial\/wp-json\/wp\/v2\/tags?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}